{"id":15435,"date":"2022-04-22T10:55:35","date_gmt":"2022-04-22T08:55:35","guid":{"rendered":"https:\/\/www.intimina.com\/es\/blog\/?p=15435"},"modified":"2022-04-22T11:06:43","modified_gmt":"2022-04-22T09:06:43","slug":"sexualidad-ecologica-protege-al-planeta-y-a-tu-salud","status":"publish","type":"post","link":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/","title":{"rendered":"Sexualidad ecol\u00f3gica: protege al planeta y a tu salud"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El movimiento ecologista, defensor del medio ambiente y comprometido con la salud del ser humano en equilibrio con los ecosistemas naturales, cada d\u00eda cuenta con m\u00e1s adeptos que reconocen<\/span><span style=\"font-weight: 400;\"> la importancia de cuidar el planeta y no agravar la crisis medioambiental que lo devasta, as\u00ed como la necesidad de cuidarse a s\u00ed mismos como parte de ese equilibrio, con una alimentaci\u00f3n saludable, ejercicio regular, t\u00e9cnicas de relajaci\u00f3n y mayor contacto con la naturaleza.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El ecologismo y sus principios tambi\u00e9n han cambiado el modo de vivir nuestra sexualidad, por eso, algunas empresas fabrican sus productos para que sean respetuosos con el medio ambiente y con la salud del ser humano: juguetes er\u00f3ticos que se recargan con luz solar o a trav\u00e9s de un USB, protectores menstruales no contaminantes, tanto en el proceso de fabricaci\u00f3n como en los materiales empleados, incluyendo el fin de su vida \u00fatil como desechos, vibradores biocompatibles y libres de sustancias t\u00f3xicas para el organismo, geles lubricantes no testados en animales\u2026 todo un mundo que pretende conservar este en el que vivimos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfC\u00f3mo puedes sumarte al movimiento?<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Evita las pilas<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Las pilas contienen elementos t\u00f3xicos; aunque son reciclables, no todos los pa\u00edses disponen de plantas de reciclaje y el almacenamiento tras su uso no garantiza la neutralizaci\u00f3n; tampoco la garantizan procedimientos como la incineraci\u00f3n, que libera las sustancias t\u00f3xicas en forma de gas a la atm\u00f3sfera. Si adem\u00e1s no se reciclan, su grado de contaminaci\u00f3n es alt\u00edsimo: una sola pila bot\u00f3n con mercurio es capaz de contaminar 600.000 litros de agua\u2026 y el organismo de los peces y bivalvos (moluscos) que no puede eliminarlo, por lo que ser\u00e1 trasmitido al ser humano como siguiente eslab\u00f3n de la cadena alimentaria.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Otros tipos de pilas tambi\u00e9n son contaminantes y perjudiciales: por ejemplo, una de litio contamina 175.000 litros de agua y las recargables usan cadmio, peligroso tambi\u00e9n para el medio ambiente y el ser humano, puesto que afecta a los ri\u00f1ones, sistema \u00f3seo y respiratorio y adem\u00e1s provoca c\u00e1ncer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque reciclar pilas es una opci\u00f3n eco-amigable (siempre y cuando se reciclen realmente y no se almacenen) no comprar productos que las necesiten es mejor opci\u00f3n. En el mercado existen juguetes sexuales y <\/span><a href=\"https:\/\/www.intimina.com\/es\/blog\/kegelsmart-ejercitador-suelo-pelvico\/\">ejercitadores del suelo p\u00e9lvico<\/a><span style=\"font-weight: 400;\"> que funcionan bater\u00edas recargables por USB, y otros que funcionan con energ\u00eda solar sin que eso afecte a su funcionalidad.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Evita el PVC y otros productos t\u00f3xicos<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Muchos juguetes sexuales contienen policloruro de vinilo o PVC, un pl\u00e1stico cuyos componentes derivan del cloruro de sodio y del petr\u00f3leo\u00a0 e incluyen cloro, hidr\u00f3geno y carbono. Aunque la industria niega efectos t\u00f3xicos en la salud y el medio ambiente, numerosas organizaciones entre las que se encuentra Greenpeace denuncian lo contrario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> La elaboraci\u00f3n del PVC\u00a0 requiere estabilizantes, plastificadores, biocidas, pirorretardantes, materiales pesados (plomo, bario, esta\u00f1o y Zinc entre otros), ftalatos, y otros compuestos org\u00e1nicos peligrosos que se liberan durante su uso y cuando se desechan; y aunque este tipo de pl\u00e1stico es reciclable, las plantas no reciclan determinados objetos fabricados con este material, como los vibradores o dildos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos fabricantes tambi\u00e9n emplean Bisfenol, ABS, Ftalatos (tambi\u00e9n conocido en la industria como DOP o DEHP) y Plastisol (un producto resultante de la combinaci\u00f3n de PVC y Ftalatos) a pesar de ser sustancias consideradas t\u00f3xicas, carcin\u00f3genas y mut\u00e1genas por la Uni\u00f3n Europea. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunas organizaciones denuncian haber encontrado tambi\u00e9n estabilizadores de Zinc, Plomo, Esta\u00f1o, Bario o Cadmio (Metales Pesados T\u00f3xicos) que son absorbidos por la sangre de la persona que utiliza estos productos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El problema es que aunque comprobemos los materiales de los que est\u00e1n hechos, evitando a toda costa los que indiquen que contienen Ftalato, Bisfenol A, PVC y ABS, a veces se omite informaci\u00f3n y\/o se enmascaran sustancias perniciosas empleando siglas o t\u00e9rminos en las etiquetas que dan a lugar a confusi\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por ello, la elecci\u00f3n m\u00e1s ecol\u00f3gica y saludable es comprar juguetes sexuales y ejercitadores p\u00e9lvicos que est\u00e9n fabricados con <a href=\"https:\/\/www.intimina.com\/es\/blog\/silicona-grado-medico\/\" target=\"_blank\" rel=\"noopener noreferrer\">silicona de grado m\u00e9dico<\/a>, es decir, silicona aprobada por la FDA (Food and Drug Administration o Administraci\u00f3n de Medicamentos y Alimentos\u200b\u200b de Estados Unidos) porque son biocompatibles, es decir, seguras para el cuerpo humano.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cuanto a la repercusi\u00f3n medioambiental de su fabricaci\u00f3n y posterior degradaci\u00f3n, a diferencia del pl\u00e1stico, la silicona de grado m\u00e9dico no desprende gases t\u00f3xicos cuando se incinera y en el caso de que acabase en la naturaleza, se descompondr\u00eda con los a\u00f1os en part\u00edculas inocuas para el medio ambiente.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Evita compresas y tampones<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Seg\u00fan la Agencia Catalana de Residuos, una mujer usa de media a lo largo de su vida alrededor de 8000 compresas o 6000 tampones, lo que supone unos 228 kg de basura a los que hay que a\u00f1adir los kg que generan el uso de salva slips y las compresas para p\u00e9rdidas de orina. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Salvo los envases y envoltorios reciclables, la mayor parte de esa basura (que incluye aplicadores y tiras adherentes) acaba en vertederos o en el medio ambiente, en el que se mantiene como contaminante durante decenas de a\u00f1os (algunas fuentes se\u00f1alan entre 300 y 500, dependiendo de la materia utilizada). <\/span><\/p>\n<p><span style=\"font-weight: 400;\">A esto hay que sumar el coste medioambiental que implica su fabricaci\u00f3n con materiales como papel (deforestaci\u00f3n), algod\u00f3n (pesticidas y fertilizantes qu\u00edmicos) y productos t\u00f3xicos como las dioxinas (letal para animales peque\u00f1os).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como os expliqu\u00e9 en el art\u00edculo sobre las <a href=\"https:\/\/www.intimina.com\/es\/blog\/ventajas-de-las-copas-menstruales-en-verano\/\">ventajas de las copas menstruales en verano<\/a>, determinados materiales empleados en el proceso de fabricaci\u00f3n de algunas compresas y tampones como perfumes, lej\u00edas, resinas o agentes aglutinantes perjudican al medio ambiente y pueden resultar t\u00f3xicos o perjudiciales para nuestro organismo, causando infecciones, alergias, micro erosiones y enfermedades graves como el c\u00e1ncer:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Poliacrilato: asociado al <a href=\"https:\/\/www.intimina.com\/es\/blog\/sindrome-shock-toxico\/\">S\u00edndrome del Shock T\u00f3xico<\/a> o SST.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ray\u00f3n: asociado al SST, adem\u00e1s impide la transpiraci\u00f3n de la vagina aumentando la posibilidad de contraer infecciones.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Fertilizantes qu\u00edmicos y pesticidas: disruptores endocrinos (afectan al equilibrio hormonal) y cancer\u00edgenos.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Dioxinas: derivadas del procedimiento del blanqueamiento con cloro, son un compuesto muy t\u00f3xico y contaminante, dif\u00edcil de eliminar del organismo y del medio ambiente. Las dioxinas son disruptores endocrinos, cancer\u00edgenas y afectan a nuestro sistema inmunol\u00f3gico y reproductivo pudiendo causar dismenorrea, endometriosis o infertilidad, entre otros problemas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Si bien es cierto que la mayor\u00eda de los fabricantes ha eliminado estas sustancias de sus productos y otros niegan su utilizaci\u00f3n o la justifican alegando que son cantidades \u00ednfimas que no afectan al organismo, estudios como <a href=\"https:\/\/www.womensvoices.org\/menstrual-care-products\/whats-in-your-tampon\/\" target=\"_blank\" rel=\"noopener noreferrer\">este<\/a> realizado en 2018 por Women\u2019s Voices for the Earth (WVE), organizaci\u00f3n sin \u00e1nimo de lucro que pretende denunciar y eliminar los qu\u00edmicos t\u00f3xicos que da\u00f1an la salud de las mujeres y sus comunidades, advierten de lo contrario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estudio, realizado en un laboratorio independiente con muestras de tampones de marcas conocidas, revel\u00f3 que algunos contienen qu\u00edmicos t\u00f3xicos como cloruro de metileno, metiletilcetona, acetato de etilo, heptano, hexano, tolueno y disulfuro de carbono; este \u00faltimo, utilizado en la producci\u00f3n de ray\u00f3n, aumenta las posibilidades de sufrir trastornos menstruales, menopausia precoz, alteraciones hormonales y problemas cardiovasculares y neurol\u00f3gicos en las trabajadoras de las plantas de fabricaci\u00f3n. Asusta, \u00bfno es cierto?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque Women\u2019s Voices for the Earth reconoce que no hay suficientes investigaciones que determinen el impacto de estas sustancias en la salud de las mujeres que utilizan estos tampones, denuncia su existencia y se pregunta qu\u00e9 puede provocar su uso en nuestro organismo a medio y largo plazo. La verdad, yo tambi\u00e9n.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Alternativas a los productos de higiene femenina tradicionales<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Conscientes de la demanda social generada por los defensores de la sexualidad ecol\u00f3gica, algunas empresas ofrecen opciones alternativas respetuosas con el medio ambiente y saludables para las mujeres: copas menstruales, compresas reutilizables de tela, bragas menstruales, y tampones y compresas fabricados con algod\u00f3n ecol\u00f3gico y\/o materiales biodegradables. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque estas alternativas son ecoamigables, no est\u00e1n libres de perjudicar al medio ambiente. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso de las compresas y tampones fabricados con materiales biodegradables, se est\u00e1n generando los mismos kg de basura por mucho que esta acabe desapareciendo con el tiempo; en cuanto a las compresas reutilizables de tela y las bragas menstruales, aunque algunas tienen una vida \u00fatil alta, deben lavarse a mano o en lavadora (previo lavado a mano para eliminar el grueso del flujo menstrual), con el consiguiente gasto de agua y energ\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, las copas menstruales tienen una duraci\u00f3n de unos diez a\u00f1os y, a diferencia de las compresas y tampones que deben cambiarse m\u00e1ximo cada cuatro horas (cada ocho las bragas menstruales), pueden utilizarse durante doce horas, incluso con reglas copiosas, y el gasto energ\u00e9tico es m\u00ednimo pues, tras vaciar el fluido menstrual, se lavan a mano con una cantidad razonable de agua. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, como hemos visto, cuando finaliza su vida \u00fatil, se destruyen sin afectar al medio ambiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cuanto al material con el que est\u00e1n fabricadas y su repercusi\u00f3n en el organismo, la elecci\u00f3n m\u00e1s saludable es<\/span><span style=\"font-weight: 400;\"> una <a href=\"https:\/\/www.intimina.com\/es\/products\">copa menstrual<\/a> de materiales hipoalerg\u00e9nicos, preferiblemente de silicona de grado m\u00e9dico, un material no poroso<\/span><span style=\"font-weight: 400;\"> hipoalerg\u00e9nico, sin l\u00e1tex ni toxinas y resistente al crecimiento de bacterias, que evita infecciones siempre y cuando se use y limpie de la manera adecuada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Finalmente, en lo relativo a los salva slip y las compresas para p\u00e9rdidas de orina, recuerda que los profesionales recomiendan que evitemos o reduzcamos el uso de los primeros porque afectan a la humedad vaginal, propiciando la aparici\u00f3n de infecciones y alergias; y en cuanto a las segundas, la debilidad del <a href=\"https:\/\/www.intimina.com\/es\/blog\/suelo-pelvico\/\">suelo p\u00e9lvico<\/a> causante de la incontinencia urinaria puede tratarse siempre que acudas a un profesional para que elabore un diagn\u00f3stico personalizado de tu caso y luego realices los ejercicios indicados para fortalecer tu musculatura.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como puedes ver hay muchas opciones para que disfrutes de una sexualidad ecol\u00f3gica respetuosa con el medio ambiente y tu salud. Hagamos un esfuerzo por nosotras, por la Tierra, por todo lo que la habita.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El movimiento ecologista, defensor del medio ambiente y comprometido con la salud del ser humano en equilibrio con los ecosistemas naturales, cada d\u00eda cuenta con m\u00e1s adeptos que reconocen la&hellip;<\/p>\n","protected":false},"author":18,"featured_media":16074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[2,6],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Consejos para una sexualidad saludable y ecol\u00f3gica<\/title>\n<meta name=\"description\" content=\"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consejos para una sexualidad saludable y ecol\u00f3gica\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de INTIMINA en espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-22T08:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-22T09:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2020\/09\/INTIMINA-37-5-eco-friendly-tips.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"865\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brenda B. Lennox\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brenda B. Lennox\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\"},\"author\":{\"name\":\"Brenda B. Lennox\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/7be9257b8096ffffbc05b3375f9cc8d0\"},\"headline\":\"Sexualidad ecol\u00f3gica: protege al planeta y a tu salud\",\"datePublished\":\"2022-04-22T08:55:35+00:00\",\"dateModified\":\"2022-04-22T09:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\"},\"wordCount\":1752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#organization\"},\"articleSection\":[\"Menstruaci\u00f3n\",\"Suelo p\u00e9lvico\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\",\"url\":\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\",\"name\":\"Consejos para una sexualidad saludable y ecol\u00f3gica\",\"isPartOf\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#website\"},\"datePublished\":\"2022-04-22T08:55:35+00:00\",\"dateModified\":\"2022-04-22T09:06:43+00:00\",\"description\":\"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#website\",\"url\":\"https:\/\/www.intimina.com\/es\/blog\/\",\"name\":\"Blog de INTIMINA en espa\u00f1ol\",\"description\":\"Todo lo que necesitas saber sobre salud y bienestar \u00edntimo femenino\",\"publisher\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intimina.com\/es\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#organization\",\"name\":\"Intimina\",\"url\":\"https:\/\/www.intimina.com\/es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2019\/04\/INTIMINA_logo-02.png\",\"contentUrl\":\"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2019\/04\/INTIMINA_logo-02.png\",\"width\":1000,\"height\":543,\"caption\":\"Intimina\"},\"image\":{\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/7be9257b8096ffffbc05b3375f9cc8d0\",\"name\":\"Brenda B. Lennox\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc0cfe2bf9a3a3c27830d0c41cefed13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc0cfe2bf9a3a3c27830d0c41cefed13?s=96&d=mm&r=g\",\"caption\":\"Brenda B. Lennox\"},\"description\":\"Brenda B. Lennox es el seud\u00f3nimo de una escritora con varios premios literarios a su espalda. La m\u00e1scara que le permite mostrar su lado m\u00e1s salvaje en textos er\u00f3ticos que destilan crudeza no exenta de humor negro y poes\u00eda. La firma que avala su compromiso con la sexualidad y la salud femenina en art\u00edculos para medios como Volont\u00e9 o Intimina.\",\"url\":\"https:\/\/www.intimina.com\/es\/blog\/author\/brenda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consejos para una sexualidad saludable y ecol\u00f3gica","description":"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/","og_locale":"en_US","og_type":"article","og_title":"Consejos para una sexualidad saludable y ecol\u00f3gica","og_description":"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!","og_url":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/","og_site_name":"Blog de INTIMINA en espa\u00f1ol","article_published_time":"2022-04-22T08:55:35+00:00","article_modified_time":"2022-04-22T09:06:43+00:00","og_image":[{"width":865,"height":485,"url":"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2020\/09\/INTIMINA-37-5-eco-friendly-tips.jpg","type":"image\/jpeg"}],"author":"Brenda B. Lennox","twitter_misc":{"Written by":"Brenda B. Lennox","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/#article","isPartOf":{"@id":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/"},"author":{"name":"Brenda B. Lennox","@id":"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/7be9257b8096ffffbc05b3375f9cc8d0"},"headline":"Sexualidad ecol\u00f3gica: protege al planeta y a tu salud","datePublished":"2022-04-22T08:55:35+00:00","dateModified":"2022-04-22T09:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/"},"wordCount":1752,"commentCount":0,"publisher":{"@id":"https:\/\/www.intimina.com\/es\/blog\/#organization"},"articleSection":["Menstruaci\u00f3n","Suelo p\u00e9lvico"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/","url":"https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/","name":"Consejos para una sexualidad saludable y ecol\u00f3gica","isPartOf":{"@id":"https:\/\/www.intimina.com\/es\/blog\/#website"},"datePublished":"2022-04-22T08:55:35+00:00","dateModified":"2022-04-22T09:06:43+00:00","description":"\u00bfTe preocupa el medio ambiente? Aprende en este art\u00edculo c\u00f3mo vivir una sexualidad ecol\u00f3gica y \u00a1s\u00famate al movimiento!","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intimina.com\/es\/blog\/sexualidad-ecologica-protege-al-planeta-y-a-tu-salud\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.intimina.com\/es\/blog\/#website","url":"https:\/\/www.intimina.com\/es\/blog\/","name":"Blog de INTIMINA en espa\u00f1ol","description":"Todo lo que necesitas saber sobre salud y bienestar \u00edntimo femenino","publisher":{"@id":"https:\/\/www.intimina.com\/es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intimina.com\/es\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.intimina.com\/es\/blog\/#organization","name":"Intimina","url":"https:\/\/www.intimina.com\/es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2019\/04\/INTIMINA_logo-02.png","contentUrl":"https:\/\/www.intimina.com\/es\/blog\/wp-content\/uploads\/2019\/04\/INTIMINA_logo-02.png","width":1000,"height":543,"caption":"Intimina"},"image":{"@id":"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/7be9257b8096ffffbc05b3375f9cc8d0","name":"Brenda B. Lennox","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intimina.com\/es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc0cfe2bf9a3a3c27830d0c41cefed13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc0cfe2bf9a3a3c27830d0c41cefed13?s=96&d=mm&r=g","caption":"Brenda B. Lennox"},"description":"Brenda B. Lennox es el seud\u00f3nimo de una escritora con varios premios literarios a su espalda. La m\u00e1scara que le permite mostrar su lado m\u00e1s salvaje en textos er\u00f3ticos que destilan crudeza no exenta de humor negro y poes\u00eda. La firma que avala su compromiso con la sexualidad y la salud femenina en art\u00edculos para medios como Volont\u00e9 o Intimina.","url":"https:\/\/www.intimina.com\/es\/blog\/author\/brenda\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/posts\/15435"}],"collection":[{"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=15435"}],"version-history":[{"count":1,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/posts\/15435\/revisions"}],"predecessor-version":[{"id":15437,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/posts\/15435\/revisions\/15437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/media\/16074"}],"wp:attachment":[{"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=15435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/categories?post=15435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intimina.com\/es\/blog\/wp-json\/wp\/v2\/tags?post=15435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}